{"id":9076,"date":"2018-01-23T16:05:00","date_gmt":"2018-01-23T16:05:00","guid":{"rendered":"https:\/\/momsteel.com.pt\/ampliacao-de-unidade-industrial-em-crolles-franca\/"},"modified":"2026-05-11T15:39:01","modified_gmt":"2026-05-11T15:39:01","slug":"ampliacao-de-unidade-industrial-em-crolles-franca","status":"publish","type":"post","link":"https:\/\/momsteel.com.pt\/es\/ampliacao-de-unidade-industrial-em-crolles-franca\/","title":{"rendered":"Ampliaci\u00f3n de una planta industrial en Crolles, Francia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9076\" class=\"elementor elementor-9076 elementor-2469\">\n\t\t\t\t<div class=\"elementor-element elementor-element-187bca9 e-flex e-con-boxed e-con e-parent\" data-id=\"187bca9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-944e573 e-con-full e-flex e-con e-child\" data-id=\"944e573\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1467439 elementor-align-left elementor-widget elementor-widget-raven-heading\" data-id=\"1467439\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"raven-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\"><h2 class=\"raven-heading raven-heading-h2\"><span class=\"raven-heading-title \">Ampliaci\u00f3n de una planta industrial en Crolles, Francia<\/span><\/h2><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2138ae2 elementor-align-flex-start elementor-widget elementor-widget-raven-breadcrumbs\" data-id=\"2138ae2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"raven-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"raven-breadcrumbs raven-breadcrumbs-yoast\"><div id=\"breadcrumbs\"><span><span><a href=\"https:\/\/momsteel.com.pt\/es\/\">Home<\/a><\/span><\/span><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90cb3c9 elementor-widget elementor-widget-text-editor\" data-id=\"90cb3c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t23 de enero de 2018\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-98f2539 e-con-full e-flex e-con e-child\" data-id=\"98f2539\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a941469 e-flex e-con-boxed e-con e-parent\" data-id=\"a941469\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-027eaee e-con-full e-flex e-con e-child\" data-id=\"027eaee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bb27067 elementor-align-left elementor-widget elementor-widget-raven-heading\" data-id=\"bb27067\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"raven-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\"><h2 class=\"raven-heading raven-heading-h2\"><span class=\"raven-heading-title \">Herdade da Malhadinha Nova, en Albernoa, Beja<\/span><\/h2><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dab3f6 elementor-widget elementor-widget-text-editor\" data-id=\"1dab3f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El <em>know-how<\/em> acumulado a lo largo de los a\u00f1os por MOMSTEEL en la ejecuci\u00f3n de proyectos de plantas industriales en el extranjero ya es de gran valor. Se trata de proyectos complejos que requieren la implicaci\u00f3n de recursos y capacidades t\u00e9cnicas de alto nivel, as\u00ed como una gesti\u00f3n operativa r\u00e1pida y profesional. Con un plazo de ejecuci\u00f3n de 35 d\u00edas, la ampliaci\u00f3n de la planta industrial de STMicroeletronics, en Crolles, Francia, cont\u00f3 con los medios y la capacidad t\u00e9cnica necesarios para producir y colocar las aproximadamente 800\u00a0toneladas requeridas.<\/p><p>La obra incluy\u00f3 el dimensionamiento y la preparaci\u00f3n de las estructuras, la fabricaci\u00f3n y entrega en la planta industrial en menos de dos meses.<\/p><p>La ampliaci\u00f3n de este espacio industrial, preparado para inversiones en tecnolog\u00eda avanzada, ha permitido una vez m\u00e1s alcanzar altos niveles de exigencia, as\u00ed como aportar valor y <em>know-how<\/em> a los equipos de trabajo de MOMSTEEL en todas las \u00e1reas de ejecuci\u00f3n del proyecto.<\/p><p>La implicaci\u00f3n y coordinaci\u00f3n de todos estos componentes permiti\u00f3 que la ejecuci\u00f3n de este proyecto alcanzara una gesti\u00f3n operativa de excelencia y el cumplimiento del plazo acordado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-540b7b3 e-con-full e-flex e-con e-child\" data-id=\"540b7b3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ce2b07b e-con-full e-flex e-con e-child\" data-id=\"ce2b07b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3af1b56 elementor-widget elementor-widget-raven-image\" data-id=\"3af1b56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-image\">\n\t\t\n\t\t\n\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/momsteel.com.pt\/wp-content\/uploads\/2024\/06\/1-1-1024x768-1.jpeg\" class=\"attachment-full size-full wp-image-9077\" alt=\"\" srcset=\"https:\/\/momsteel.com.pt\/wp-content\/uploads\/2024\/06\/1-1-1024x768-1.jpeg 1024w, https:\/\/momsteel.com.pt\/wp-content\/uploads\/2024\/06\/1-1-1024x768-1-367x275.jpeg 367w, https:\/\/momsteel.com.pt\/wp-content\/uploads\/2024\/06\/1-1-1024x768-1-768x576.jpeg 768w, https:\/\/momsteel.com.pt\/wp-content\/uploads\/2024\/06\/1-1-1024x768-1-200x150.jpeg 200w, https:\/\/momsteel.com.pt\/wp-content\/uploads\/2024\/06\/1-1-1024x768-1-300x225.jpeg 300w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3122ee1 e-flex e-con-boxed e-con e-parent\" data-id=\"3122ee1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-566c68c elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"566c68c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/momsteel.com.pt\/wp-content\/uploads\/2024\/06\/1-2-1024x768-1-768x576.jpeg\" alt=\"1-2-1024x768\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/momsteel.com.pt\/wp-content\/uploads\/2024\/06\/1-3-1024x768-1-768x576.jpeg\" alt=\"1-3-1024x768\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/momsteel.com.pt\/wp-content\/uploads\/2024\/06\/1-1024x768-1-768x576.jpeg\" alt=\"1-1024x768\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Proin quis magna sed ipsum venenatis ultricies. Sed maximus at lacus ac egestas. Vestibulum porttitor nulla a metus bibendum, non laoreet sapien venenatis. In tempor pellentesque mauris a aliquet. Duis ac nibh auctor dui lacinia laoreet. Mauris posuere, massa vel vehicula luctus, neque ligula dapibus ante, a posuere elit lorem non nisi. Mauris sit amet leo vehicula enim iaculis ultricies id id mauris. Aliquam erat volutpat. Interdum et malesuada fames ac ante ipsum primis in faucibus. Sed non mollis nisl. Vestibulum id dui ac tortor finibus venenatis. Nullam pharetra interdum congue. Maecenas at imperdiet risus, non accumsan lorem. Nullam elementum mauris diam, vel iaculis erat tincidunt nec. Nunc porta maximus sem, ut faucibus augue tristique non.<\/p>\n","protected":false},"author":2,"featured_media":9077,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[53],"tags":[],"class_list":["post-9076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ampliaci\u00f3n de una planta industrial en Crolles, Francia - Momsteel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/momsteel.com.pt\/es\/ampliacao-de-unidade-industrial-em-crolles-franca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ampliaci\u00f3n de una planta industrial en Crolles, Francia - Momsteel\" \/>\n<meta property=\"og:description\" content=\"Proin quis magna sed ipsum venenatis ultricies. Sed maximus at lacus ac egestas. Vestibulum porttitor nulla a metus bibendum, non laoreet sapien venenatis. In tempor pellentesque mauris a aliquet. Duis ac nibh auctor dui lacinia laoreet. Mauris posuere, massa vel vehicula luctus, neque ligula dapibus ante, a posuere elit lorem non nisi. Mauris sit amet leo vehicula enim iaculis ultricies id id mauris. Aliquam erat volutpat. Interdum et malesuada fames ac ante ipsum primis in faucibus. Sed non mollis nisl. Vestibulum id dui ac tortor finibus venenatis. Nullam pharetra interdum congue. Maecenas at imperdiet risus, non accumsan lorem. Nullam elementum mauris diam, vel iaculis erat tincidunt nec. Nunc porta maximus sem, ut faucibus augue tristique non.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/momsteel.com.pt\/es\/ampliacao-de-unidade-industrial-em-crolles-franca\/\" \/>\n<meta property=\"og:site_name\" content=\"Momsteel\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-23T16:05:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T15:39:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/momsteel.com.pt\/wp-content\/uploads\/2024\/06\/1-1-1024x768-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Beatriz Assun\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Beatriz Assun\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/ampliacao-de-unidade-industrial-em-crolles-franca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/ampliacao-de-unidade-industrial-em-crolles-franca\\\/\"},\"author\":{\"name\":\"Beatriz Assun\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/#\\\/schema\\\/person\\\/666b22432248a2231f606c293c451887\"},\"headline\":\"Ampliaci\u00f3n de una planta industrial en Crolles, Francia\",\"datePublished\":\"2018-01-23T16:05:00+00:00\",\"dateModified\":\"2026-05-11T15:39:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/ampliacao-de-unidade-industrial-em-crolles-franca\\\/\"},\"wordCount\":218,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/ampliacao-de-unidade-industrial-em-crolles-franca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/momsteel.com.pt\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/1-1-1024x768-1.jpeg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/ampliacao-de-unidade-industrial-em-crolles-franca\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/ampliacao-de-unidade-industrial-em-crolles-franca\\\/\",\"url\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/ampliacao-de-unidade-industrial-em-crolles-franca\\\/\",\"name\":\"Ampliaci\u00f3n de una planta industrial en Crolles, Francia - Momsteel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/ampliacao-de-unidade-industrial-em-crolles-franca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/ampliacao-de-unidade-industrial-em-crolles-franca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/momsteel.com.pt\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/1-1-1024x768-1.jpeg\",\"datePublished\":\"2018-01-23T16:05:00+00:00\",\"dateModified\":\"2026-05-11T15:39:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/ampliacao-de-unidade-industrial-em-crolles-franca\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/ampliacao-de-unidade-industrial-em-crolles-franca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/ampliacao-de-unidade-industrial-em-crolles-franca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/momsteel.com.pt\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/1-1-1024x768-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/momsteel.com.pt\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/1-1-1024x768-1.jpeg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/ampliacao-de-unidade-industrial-em-crolles-franca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ampliaci\u00f3n de una planta industrial en Crolles, Francia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/\",\"name\":\"Momsteel\",\"description\":\"MOMSTEEL \u2013 EIFFAGE \u00e9 uma refer\u00eancia na conce\u00e7\u00e3o e constru\u00e7\u00e3o de estruturas met\u00e1licas, entregues no prazo acordado e com uma pegada ecol\u00f3gica reduzida\",\"publisher\":{\"@id\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/#organization\"},\"alternateName\":\"MOMSTEEL \u2013 EIFFAGE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/#organization\",\"name\":\"Momsteel\",\"url\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/momsteel.com.pt\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Logotipo_MOMSteel.png\",\"contentUrl\":\"https:\\\/\\\/momsteel.com.pt\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Logotipo_MOMSteel.png\",\"width\":1644,\"height\":407,\"caption\":\"Momsteel\"},\"image\":{\"@id\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/#\\\/schema\\\/person\\\/666b22432248a2231f606c293c451887\",\"name\":\"Beatriz Assun\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20601f280c2113f218bb111ec06ab524ee50f8e084d76e94782083e1d4a28938?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20601f280c2113f218bb111ec06ab524ee50f8e084d76e94782083e1d4a28938?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20601f280c2113f218bb111ec06ab524ee50f8e084d76e94782083e1d4a28938?s=96&d=mm&r=g\",\"caption\":\"Beatriz Assun\u00e7\u00e3o\"},\"url\":\"https:\\\/\\\/momsteel.com.pt\\\/es\\\/author\\\/beatriz-assuncaomomsteel-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ampliaci\u00f3n de una planta industrial en Crolles, Francia - Momsteel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/momsteel.com.pt\/es\/ampliacao-de-unidade-industrial-em-crolles-franca\/","og_locale":"es_ES","og_type":"article","og_title":"Ampliaci\u00f3n de una planta industrial en Crolles, Francia - Momsteel","og_description":"Proin quis magna sed ipsum venenatis ultricies. Sed maximus at lacus ac egestas. Vestibulum porttitor nulla a metus bibendum, non laoreet sapien venenatis. In tempor pellentesque mauris a aliquet. Duis ac nibh auctor dui lacinia laoreet. Mauris posuere, massa vel vehicula luctus, neque ligula dapibus ante, a posuere elit lorem non nisi. Mauris sit amet leo vehicula enim iaculis ultricies id id mauris. Aliquam erat volutpat. Interdum et malesuada fames ac ante ipsum primis in faucibus. Sed non mollis nisl. Vestibulum id dui ac tortor finibus venenatis. Nullam pharetra interdum congue. Maecenas at imperdiet risus, non accumsan lorem. Nullam elementum mauris diam, vel iaculis erat tincidunt nec. Nunc porta maximus sem, ut faucibus augue tristique non.","og_url":"https:\/\/momsteel.com.pt\/es\/ampliacao-de-unidade-industrial-em-crolles-franca\/","og_site_name":"Momsteel","article_published_time":"2018-01-23T16:05:00+00:00","article_modified_time":"2026-05-11T15:39:01+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/momsteel.com.pt\/wp-content\/uploads\/2024\/06\/1-1-1024x768-1.jpeg","type":"image\/jpeg"}],"author":"Beatriz Assun\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Beatriz Assun\u00e7\u00e3o","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/momsteel.com.pt\/es\/ampliacao-de-unidade-industrial-em-crolles-franca\/#article","isPartOf":{"@id":"https:\/\/momsteel.com.pt\/es\/ampliacao-de-unidade-industrial-em-crolles-franca\/"},"author":{"name":"Beatriz Assun\u00e7\u00e3o","@id":"https:\/\/momsteel.com.pt\/es\/#\/schema\/person\/666b22432248a2231f606c293c451887"},"headline":"Ampliaci\u00f3n de una planta industrial en Crolles, Francia","datePublished":"2018-01-23T16:05:00+00:00","dateModified":"2026-05-11T15:39:01+00:00","mainEntityOfPage":{"@id":"https:\/\/momsteel.com.pt\/es\/ampliacao-de-unidade-industrial-em-crolles-franca\/"},"wordCount":218,"commentCount":0,"publisher":{"@id":"https:\/\/momsteel.com.pt\/es\/#organization"},"image":{"@id":"https:\/\/momsteel.com.pt\/es\/ampliacao-de-unidade-industrial-em-crolles-franca\/#primaryimage"},"thumbnailUrl":"https:\/\/momsteel.com.pt\/wp-content\/uploads\/2024\/06\/1-1-1024x768-1.jpeg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/momsteel.com.pt\/es\/ampliacao-de-unidade-industrial-em-crolles-franca\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/momsteel.com.pt\/es\/ampliacao-de-unidade-industrial-em-crolles-franca\/","url":"https:\/\/momsteel.com.pt\/es\/ampliacao-de-unidade-industrial-em-crolles-franca\/","name":"Ampliaci\u00f3n de una planta industrial en Crolles, Francia - Momsteel","isPartOf":{"@id":"https:\/\/momsteel.com.pt\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/momsteel.com.pt\/es\/ampliacao-de-unidade-industrial-em-crolles-franca\/#primaryimage"},"image":{"@id":"https:\/\/momsteel.com.pt\/es\/ampliacao-de-unidade-industrial-em-crolles-franca\/#primaryimage"},"thumbnailUrl":"https:\/\/momsteel.com.pt\/wp-content\/uploads\/2024\/06\/1-1-1024x768-1.jpeg","datePublished":"2018-01-23T16:05:00+00:00","dateModified":"2026-05-11T15:39:01+00:00","breadcrumb":{"@id":"https:\/\/momsteel.com.pt\/es\/ampliacao-de-unidade-industrial-em-crolles-franca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/momsteel.com.pt\/es\/ampliacao-de-unidade-industrial-em-crolles-franca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/momsteel.com.pt\/es\/ampliacao-de-unidade-industrial-em-crolles-franca\/#primaryimage","url":"https:\/\/momsteel.com.pt\/wp-content\/uploads\/2024\/06\/1-1-1024x768-1.jpeg","contentUrl":"https:\/\/momsteel.com.pt\/wp-content\/uploads\/2024\/06\/1-1-1024x768-1.jpeg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/momsteel.com.pt\/es\/ampliacao-de-unidade-industrial-em-crolles-franca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/momsteel.com.pt\/es\/"},{"@type":"ListItem","position":2,"name":"Ampliaci\u00f3n de una planta industrial en Crolles, Francia"}]},{"@type":"WebSite","@id":"https:\/\/momsteel.com.pt\/es\/#website","url":"https:\/\/momsteel.com.pt\/es\/","name":"Momsteel","description":"MOMSTEEL \u2013 EIFFAGE \u00e9 uma refer\u00eancia na conce\u00e7\u00e3o e constru\u00e7\u00e3o de estruturas met\u00e1licas, entregues no prazo acordado e com uma pegada ecol\u00f3gica reduzida","publisher":{"@id":"https:\/\/momsteel.com.pt\/es\/#organization"},"alternateName":"MOMSTEEL \u2013 EIFFAGE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/momsteel.com.pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/momsteel.com.pt\/es\/#organization","name":"Momsteel","url":"https:\/\/momsteel.com.pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/momsteel.com.pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/momsteel.com.pt\/wp-content\/uploads\/2024\/07\/Logotipo_MOMSteel.png","contentUrl":"https:\/\/momsteel.com.pt\/wp-content\/uploads\/2024\/07\/Logotipo_MOMSteel.png","width":1644,"height":407,"caption":"Momsteel"},"image":{"@id":"https:\/\/momsteel.com.pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/momsteel.com.pt\/es\/#\/schema\/person\/666b22432248a2231f606c293c451887","name":"Beatriz Assun\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/20601f280c2113f218bb111ec06ab524ee50f8e084d76e94782083e1d4a28938?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/20601f280c2113f218bb111ec06ab524ee50f8e084d76e94782083e1d4a28938?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20601f280c2113f218bb111ec06ab524ee50f8e084d76e94782083e1d4a28938?s=96&d=mm&r=g","caption":"Beatriz Assun\u00e7\u00e3o"},"url":"https:\/\/momsteel.com.pt\/es\/author\/beatriz-assuncaomomsteel-com\/"}]}},"_links":{"self":[{"href":"https:\/\/momsteel.com.pt\/es\/wp-json\/wp\/v2\/posts\/9076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/momsteel.com.pt\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/momsteel.com.pt\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/momsteel.com.pt\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/momsteel.com.pt\/es\/wp-json\/wp\/v2\/comments?post=9076"}],"version-history":[{"count":8,"href":"https:\/\/momsteel.com.pt\/es\/wp-json\/wp\/v2\/posts\/9076\/revisions"}],"predecessor-version":[{"id":10210,"href":"https:\/\/momsteel.com.pt\/es\/wp-json\/wp\/v2\/posts\/9076\/revisions\/10210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/momsteel.com.pt\/es\/wp-json\/wp\/v2\/media\/9077"}],"wp:attachment":[{"href":"https:\/\/momsteel.com.pt\/es\/wp-json\/wp\/v2\/media?parent=9076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/momsteel.com.pt\/es\/wp-json\/wp\/v2\/categories?post=9076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/momsteel.com.pt\/es\/wp-json\/wp\/v2\/tags?post=9076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}